{"id":3483,"date":"2022-11-01T08:00:00","date_gmt":"2022-11-01T07:00:00","guid":{"rendered":"https:\/\/www.opisto.fr\/fr\/entreprise\/?p=3483"},"modified":"2022-11-14T11:10:56","modified_gmt":"2022-11-14T10:10:56","slug":"equip-auto-2022-une-reussite-pour-opisto","status":"publish","type":"post","link":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/","title":{"rendered":"EQUIP AUTO 2022 : une r\u00e9ussite pour Opisto !"},"content":{"rendered":"\n<p>Difficile de passer \u00e0 c\u00f4t\u00e9 d\u2019Opisto lors de cette \u00e9dition 2022 d&rsquo;EQUIP AUTO ! Pr\u00e9sent sur l\u2019une des all\u00e9es principales du pavillon 1, sur le Garage du Futur ainsi que sur le stand de notre partenaire Auto Distribution, Opisto a pu rencontrer les professionnels de l&rsquo;automobile et les centres VHU durant une semaine riche en \u00e9v\u00e8nements.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png\" alt=\"EQUIP AUTO OPISTO\" class=\"wp-image-3485\" width=\"500\" height=\"293\" srcset=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1-980x573.png 980w, https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1-480x281.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, 100vw\" \/><\/figure><\/div>\n\n\n\n<p>L\u2019\u00e9quipe d\u2019Opisto a rencontr\u00e9 ses clients et a pu \u00e9changer avec une partie des <strong>78&nbsp;280 visiteurs pr\u00e9sents sur cette \u00e9dition 2022 d&rsquo;EQUIP AUTO<\/strong>. L\u2019occasion pour Opisto de pr\u00e9senter sa solution <a href=\"https:\/\/www.opisto.pro\/\">opisto.pro<\/a> aux professionnels de la r\u00e9paration (garagistes, carrossiers, etc), et de collecter leur retour en direct, apr\u00e8s 2 ann\u00e9es de pand\u00e9mie sans \u00e9v\u00e8nement physique. Avec un stand qui n\u2019a pas d\u00e9sempli de la semaine, <strong>Opisto confirme sa position de leader de la distribution en ligne de pi\u00e8ces d\u00e9tach\u00e9es pour les professionnels<\/strong> et compte continuer d\u2019asseoir sa notori\u00e9t\u00e9 dans les ann\u00e9es \u00e0 venir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"durant-une-semaine-l-equipe-d-opisto-a-rencontre-ses-clients-et-a-pu-echanger-avec-une-partie-des-78-280-visiteurs-presents-sur-cette-edition-2022-l-occasion-pour-opisto-de-presenter-sa-solution-opisto-pro-aux-professionnels-de-la-reparation-garagistes-carrossiers-etc-et-de-collecter-leur-retour-en-direct-apres-2-annees-de-pandemie-sans-contact-humain-avec-un-stand-qui-n-a-pas-desempli-de-la-semaine-opisto-affirme-sa-position-de-leader-de-la-distribution-en-ligne-de-pieces-detachees-pour-les-professionnels-et-compte-continuer-d-asseoir-sa-notoriete-dans-les-annees-a-venir-la-filiere-pre-mise-a-l-honneur-sur-equip-auto\"><strong><strong>La fili\u00e8re VHU mise \u00e0 l&rsquo;honneur sur EQUIP AUTO<\/strong><\/strong><\/h2>\n\n\n\n<p>Cette semaine a \u00e9galement \u00e9t\u00e9 l\u2019occasion de rencontrer nos clients d\u00e9molisseurs \u00e9quip\u00e9s du logiciel Opisto 360. Les centres VHU partenaires d\u2019Opisto ayant fait le d\u00e9placement pour rencontrer l\u2019\u00e9quipe voire profiter de diagnostics gratuits de leur activit\u00e9, ont \u00e9galement pu d\u00e9couvrir l\u2019une des nouveaut\u00e9s \u00e0 venir sur notre application mobile.<\/p>\n\n\n\n<p>Nos partenaires ne sont pas repartis les mains vides, puisque 100 kits CVHU remplis de cadeaux pour eux et leur \u00e9quipe ont \u00e9t\u00e9 remis. 3 d\u2019entre eux ont eu la chance de d\u00e9couvrir dans leur kit un Ticket d\u2019Or Opisto&nbsp;! Une nouveaut\u00e9 qui permet \u00e0 <strong>CUB AC CASSE, RN 74 et PARIS AUTOMOBILE RECYCLAGE<\/strong> de remporter chacun un bon de 500\u20ac de team building&nbsp;! Opisto est ravi de pouvoir offrir un moment convivial aux \u00e9quipes de nos partenaires, qui \u0153uvrent \u00e0 nos c\u00f4t\u00e9s chaque jour pour digitaliser les pi\u00e8ces auto d\u2019occasion.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3486\" src=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00043-small.png\" alt=\"EQUIP AUTO OPISTO\" class=\"wp-image-3486\" srcset=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00043-small.png 500w, https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00043-small-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3487\" src=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00053-small.png\" alt=\"EQUIP AUTO OPISTO\" class=\"wp-image-3487\" srcset=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00053-small.png 500w, https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00053-small-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3488\" src=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00052-small.png\" alt=\"EQUIP AUTO OPISTO\" class=\"wp-image-3488\" srcset=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00052-small.png 500w, https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00052-small-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<p>EQUIP AUTO 2022 a \u00e9galement \u00e9t\u00e9 le moment de r\u00e9compenser certains acteurs de la fili\u00e8re de traitement des v\u00e9hicules hors d\u2019usage. 280 acteurs ont ainsi assist\u00e9 \u00e0 la <a href=\"https:\/\/autorecyclage.com\/actualites\/11eme-edition-des-trophees-auto-recyclage-mobilises\" target=\"_blank\" rel=\"noreferrer noopener\">11<sup>e<\/sup> \u00e9dition des Troph\u00e9es Auto Recyclage<\/a>, une participation record. Partenaire de l\u2019\u00e9v\u00e8nement et membre du Jury, c\u2019est avec fiert\u00e9 qu\u2019Opisto a pu voir de nombreux centres partenaires r\u00e9compens\u00e9s pour leur performance&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Troph\u00e9e \u00ab\u00a0TRV R\u00e9utilisation Valorisation &#8211; Plus de 2 000 VHU\u00a0\u00bb :\u00a0<strong>Auto Moto Center Car\u00e9co Avignon<\/strong><\/li><li>Troph\u00e9e \u00ab\u00a0TRV R\u00e9utilisation Valorisation &#8211; Moins de 2 000 VHU\u00a0\u00bb :\u00a0<strong>Magique Pi\u00e8ces Auto<\/strong><\/li><li>Troph\u00e9e \u00ab\u00a0R\u00e9emploi pi\u00e8ces \/ VHU &#8211; Plus de\u00a0 2 000 VHU\u00a0\u00bb :\u00a0<strong>Euro Casse<\/strong><\/li><li>Troph\u00e9e \u00ab\u00a0Gestion de l&rsquo;eau\u00a0\u00bb :\u00a0<strong>Auto Pi\u00e8ces 51<\/strong><\/li><li>Troph\u00e9e \u00ab\u00a0D\u00e9veloppement\u00a0\u00bb :<strong> Auto Pi\u00e8ces 37\u00a0<\/strong><\/li><li>Troph\u00e9e \u00ab\u00a0Coup de c\u0153ur\u00a0\u00bb :\u00a0<strong>Alberdi<\/strong><\/li><li>Troph\u00e9e \u00ab\u00a0Auto Recyclage\u00a0\u00bb\u00a0:\u00a0<strong>Provence Moto Casse<\/strong>\u00a0<\/li><li>Mention Sp\u00e9ciale du Jury : <strong>Gizzi D\u00e9molition<\/strong> (prix remis par Opisto)<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/MG_8184-small.png\" alt=\"EQUIP AUTO OPISTO\" class=\"wp-image-3489\" width=\"465\" height=\"300\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"vers-un-secteur-automobile-plus-vert\"><strong><strong>Vers un secteur automobile plus vert<\/strong><\/strong><\/h2>\n\n\n\n<p>\u00c9galement pr\u00e9sent sur le Garage du Futur aux c\u00f4t\u00e9s d\u2019autres entreprises innovantes, il \u00e9tait essentiel pour Opisto d\u2019affirmer que le garage de demain devra \u00eatre \u00e9cologique et durable, gr\u00e2ce notamment au recyclage des pi\u00e8ces automobiles. Cet engagement pour un secteur plus vert, a \u00e9galement pu \u00eatre d\u00e9fendu lors de deux conf\u00e9rences auxquelles Opisto intervenait :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Grand Forum Europ\u00e9en #1 : Transition \u00e9cologique, \u00e9conomie circulaire : les grands enjeux pour l&rsquo;apr\u00e8s-vente automobile, 2022-2030<\/li><li>Conf\u00e9rence Sp\u00e9ciale Pi\u00e8ces de R\u00e9-emploi (PIEC) : les conditions du succ\u00e8s <\/li><\/ul>\n\n\n\n<p>Des moments d\u2019\u00e9change et de d\u00e9bats entre acteurs de l\u2019automobile, qui contribuent \u00e0 \u00e9veiller les consciences de chacun sur l\u2019importance de l\u2019\u00e9conomie circulaire dans l\u2019avenir de notre secteur.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00025-small.png\" alt=\"EQUIP AUTO OPISTO\" class=\"wp-image-3490\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00025-small.png 500w, https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00025-small-480x360.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/><\/figure><\/div>\n\n\n\n<p>Fort du succ\u00e8s de cette \u00e9dition 2022, Opisto tient \u00e0 remercier chaque partenaire et chaque client ayant fait le d\u00e9placement pour rencontrer notre \u00e9quipe. Notre \u00e9quipe vous donne d\u2019ores et d\u00e9j\u00e0 rendez-vous fin 2023 pour une nouvelle \u00e9dition d\u2019EQUIP AUTO&nbsp;\u00e0 Lyon&nbsp;!<\/p>\n\n\n\n<p><a id=\"_msocom_1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durant une semaine, l\u2019\u00e9quipe d\u2019Opisto a rencontr\u00e9 ses clients et a pu \u00e9changer avec une partie des 78\u00a0280 visiteurs pr\u00e9sents sur cette \u00e9dition 2022. L\u2019occasion pour Opisto de pr\u00e9senter sa solution opisto.pro aux professionnels de la r\u00e9paration (garagistes, carrossiers, etc), et de collecter leur retour<\/p>\n","protected":false},"author":9,"featured_media":3485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:image {\"id\":2706,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2021\/10\/2.jpg\" alt=\"\" class=\"wp-image-2706\"\/><figcaption>Pi\u00e8ces auto d'occasion entrepos\u00e9es dans un Centre pour V\u00e9hicules Hors d'Usage.<\/figcaption><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:pullquote -->\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le march\u00e9 de la pi\u00e8ce auto d'occasion en France est en pleine mutation et offre aujourd'hui de nombreux b\u00e9n\u00e9fices. Mais quels sont-ils concr\u00e8tement ?<\/p><p><\/p><\/blockquote><\/figure>\n<!-- \/wp:pullquote -->\n\n<!-- wp:heading -->\n<h2>Un march\u00e9 qui peine \u00e0 d\u00e9coller en France<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:spacer {\"height\":23} -->\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:paragraph -->\n<p>Aux Etats-Unis, la part de march\u00e9 des pi\u00e8ces auto d'occasion s'\u00e9l\u00e8ve \u00e0 20 % contre 5 % en France. Ce d\u00e9calage s\u2019explique par le fait qu\u2019en France, le march\u00e9 de la pi\u00e8ce d\u2019occasion a \u00e9t\u00e9 pendant tr\u00e8s longtemps assimil\u00e9 \u00e0 la casse automobile \u00e0 l\u2019ancienne.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pourtant, ces 4 derni\u00e8res ann\u00e9es, le march\u00e9 de la pi\u00e8ce d\u2019occasion s\u2019est m\u00e9tamorphos\u00e9, professionnalis\u00e9. La digitalisation croissante des pi\u00e8ces de r\u00e9emploi a permis de qualifier et quantifier l\u2019offre. Elle a pris une dimension nationale, tant \u00e0 destination des particuliers que des professionnels. Sa part de march\u00e9 ne cesse de progresser sous l\u2019impulsion de la r\u00e9glementation et de l\u2019\u00e9volution raisonn\u00e9e des comportements de consommation.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Cette mont\u00e9e en gamme permet \u00e0 des acteurs beaucoup plus importants - r\u00e9seaux de distribution, assureurs, experts - de mettre en avant la pi\u00e8ce de r\u00e9emploi pour r\u00e9parer les v\u00e9hicules de leurs clients. Toutefois, cette offre s\u2019est structur\u00e9e assez tard en France, ce qui explique en partie le d\u00e9calage observ\u00e9 avec les Etats-Unis.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:spacer {\"height\":19} -->\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:spacer {\"height\":23} -->\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:heading -->\n<h2>La pi\u00e8ce auto d'occasion : moins ch\u00e8re et plus verte !<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Acheter de l\u2019occasion permet d\u2019\u00e9conomiser entre 50 et 70&nbsp;% par rapport \u00e0 la valeur du prix chez un constructeur.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Depuis 2018, le code de la consommation a d\u00e9clar\u00e9 que les garagistes doivent obligatoirement proposer des pi\u00e8ces de rechange \u00e0 leurs clients pour la r\u00e9paration de leur voiture.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Cette loi s\u2019applique \u00e0 tous les professionnels qui fournissent des services et prestations de r\u00e9paration ou d\u2019entretien. Ils ont l\u2019obligation de proposer des pi\u00e8ces de r\u00e9emploi \u00e0 leurs clients.Cependant, ces derniers ne sont pas oblig\u00e9s de donner une suite favorable \u00e0 leur proposition. Le professionnel doit donc proposer deux devis diff\u00e9rents :<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>Un premier avec les prix des pi\u00e8ces d\u2019occasion,<\/li><li>Et un second avec les pi\u00e8ces neuves \u00e0 ses clients.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>La relance \u00e9conomique doit \u00eatre plus verte et l\u2019\u00e9conomie circulaire va y prendre toute sa part. Les consommateurs en ont conscience et pl\u00e9biscitent de plus en plus l\u2019achat d\u2019occasion qui allie \u00e9cologie et \u00e9conomie. Une tendance \u00e0 laquelle r\u00e9pond la pi\u00e8ce automobile de r\u00e9emploi. La pi\u00e8ce d\u2019occasion est un choix strat\u00e9gique en sachant que l\u2019automobile est le 2<sup>\u00e8me<\/sup> poste de d\u00e9pense des m\u00e9nages fran\u00e7ais.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Au-del\u00e0 de l\u2019aspect \u00e9conomique, les solutions propos\u00e9es par Opisto permettent de valoriser l\u2019\u00e9conomie circulaire et le d\u00e9veloppement durable dans le milieu de l\u2019automobile. Opisto offre ainsi une deuxi\u00e8me vie aux pi\u00e8ces d\u00e9tach\u00e9es, r\u00e9utilise l\u2019existant et produit moins de d\u00e9chets.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:spacer {\"height\":23} -->\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:image {\"id\":2707,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2021\/10\/AdobeStock_427106604-1-scaled.jpeg\" alt=\"\" class=\"wp-image-2707\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:heading -->\n<h2>Le contr\u00f4le strict des pi\u00e8ces d\u00e9tach\u00e9es <\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Afin de garantir une totale s\u00e9curit\u00e9 aux consommateurs, chaque pi\u00e8ce propos\u00e9e sur les marketplaces d\u2019Opisto a \u00e9t\u00e9 nettoy\u00e9e, contr\u00f4l\u00e9e et v\u00e9rifi\u00e9e par le CVHU dont elle est issue.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Gr\u00e2ce au stock disponible en temps r\u00e9el propos\u00e9 sur les plateformes <a href=\"http:\/\/opisto.fr\" target=\"_blank\" rel=\"noreferrer noopener\">Opisto.fr<\/a>, <a href=\"http:\/\/opisto.pro\" target=\"_blank\" rel=\"noreferrer noopener\">Opisto.pro<\/a> et <a href=\"http:\/\/opisto.com\" target=\"_blank\" rel=\"noreferrer noopener\">Opisto.com<\/a>, le client peut r\u00e9aliser sa commande rapidement et en toute confiance.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Les d\u00e9lais de livraison varient selon les vendeurs et leur capacit\u00e9 d\u2019exp\u00e9dition mais s\u2019effectuent en moyenne entre 48 et 72&nbsp;h.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Les marketplaces Opisto offre au grand public et aux professionnels de la r\u00e9paration automobile, un catalogue de plusieurs millions de pi\u00e8ces d\u2019occasion !<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>On y trouve ainsi des pi\u00e8ces de carrosserie (optiques, capots, ailes, r\u00e9troviseurs, portes, etc.), mais aussi des moteurs, bo\u00eetes de vitesses, ou encore des alternateurs.<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"categories":[103,69,21,70],"tags":[76],"class_list":["post-3483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-103","category-activite-dopisto","category-blog","category-evenement","tag-communication-opisto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EQUIP AUTO 2022 : Une r\u00e9ussite pour Opisto \u2013 Opisto<\/title>\n<meta name=\"description\" content=\"Clap de fin pour l&#039;\u00e9dition 2022 d&#039;EQUIP AUTO ! Un \u00e9v\u00e8nement auquel participait Opisto, qui a affirm\u00e9 sa position de leader de la distribution en lignes de pi\u00e8ces auto d&#039;occasion aupr\u00e8s des professionnels et centres VHU pr\u00e9sents.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EQUIP AUTO 2022 : Une r\u00e9ussite pour Opisto \u2013 Opisto\" \/>\n<meta property=\"og:description\" content=\"Clap de fin pour l&#039;\u00e9dition 2022 d&#039;EQUIP AUTO ! Un \u00e9v\u00e8nement auquel participait Opisto, qui a affirm\u00e9 sa position de leader de la distribution en lignes de pi\u00e8ces auto d&#039;occasion aupr\u00e8s des professionnels et centres VHU pr\u00e9sents.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/\" \/>\n<meta property=\"og:site_name\" content=\"Opisto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/opisto.fr\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-01T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-14T10:10:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Oc\u00e9ane PAGNOUX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Opisto_fr\" \/>\n<meta name=\"twitter:site\" content=\"@Opisto_fr\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/\"},\"author\":{\"name\":\"Oc\u00e9ane PAGNOUX\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/person\/73c1ad08f94cde732413b5ddc363797a\"},\"headline\":\"EQUIP AUTO 2022 : une r\u00e9ussite pour Opisto !\",\"datePublished\":\"2022-11-01T07:00:00+00:00\",\"dateModified\":\"2022-11-14T10:10:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/\"},\"wordCount\":668,\"publisher\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png\",\"keywords\":[\"Communication Opisto\"],\"articleSection\":[\"2022\",\"Activit\u00e9 d'Opisto\",\"Blog\",\"Ev\u00e9nement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/\",\"url\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/\",\"name\":\"EQUIP AUTO 2022 : Une r\u00e9ussite pour Opisto \u2013 Opisto\",\"isPartOf\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png\",\"datePublished\":\"2022-11-01T07:00:00+00:00\",\"dateModified\":\"2022-11-14T10:10:56+00:00\",\"description\":\"Clap de fin pour l'\u00e9dition 2022 d'EQUIP AUTO ! Un \u00e9v\u00e8nement auquel participait Opisto, qui a affirm\u00e9 sa position de leader de la distribution en lignes de pi\u00e8ces auto d'occasion aupr\u00e8s des professionnels et centres VHU pr\u00e9sents.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#primaryimage\",\"url\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png\",\"contentUrl\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png\",\"width\":1000,\"height\":585,\"caption\":\"EQUIP AUTO OPISTO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/category\/blog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EQUIP AUTO 2022 : une r\u00e9ussite pour Opisto !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#website\",\"url\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/\",\"name\":\"Opisto\",\"description\":\"Le sp\u00e9cialiste des pi\u00e8ces auto d\u2019occasion\",\"publisher\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#organization\"},\"alternateName\":\"Opisto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#organization\",\"name\":\"Opisto\",\"alternateName\":\"Opisto\",\"url\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2023\/11\/logo-opisto.svg\",\"contentUrl\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2023\/11\/logo-opisto.svg\",\"width\":226,\"height\":79,\"caption\":\"Opisto\"},\"image\":{\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/opisto.fr\",\"https:\/\/x.com\/Opisto_fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/person\/73c1ad08f94cde732413b5ddc363797a\",\"name\":\"Oc\u00e9ane PAGNOUX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0ad6494a29073d76fcaf6fc719942093?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0ad6494a29073d76fcaf6fc719942093?s=96&d=mm&r=g\",\"caption\":\"Oc\u00e9ane PAGNOUX\"},\"url\":\"https:\/\/www.opisto.fr\/fr\/entreprise\/author\/oceane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EQUIP AUTO 2022 : Une r\u00e9ussite pour Opisto \u2013 Opisto","description":"Clap de fin pour l'\u00e9dition 2022 d'EQUIP AUTO ! Un \u00e9v\u00e8nement auquel participait Opisto, qui a affirm\u00e9 sa position de leader de la distribution en lignes de pi\u00e8ces auto d'occasion aupr\u00e8s des professionnels et centres VHU pr\u00e9sents.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/","og_locale":"fr_FR","og_type":"article","og_title":"EQUIP AUTO 2022 : Une r\u00e9ussite pour Opisto \u2013 Opisto","og_description":"Clap de fin pour l'\u00e9dition 2022 d'EQUIP AUTO ! Un \u00e9v\u00e8nement auquel participait Opisto, qui a affirm\u00e9 sa position de leader de la distribution en lignes de pi\u00e8ces auto d'occasion aupr\u00e8s des professionnels et centres VHU pr\u00e9sents.","og_url":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/","og_site_name":"Opisto","article_publisher":"https:\/\/web.facebook.com\/opisto.fr","article_published_time":"2022-11-01T07:00:00+00:00","article_modified_time":"2022-11-14T10:10:56+00:00","og_image":[{"width":1000,"height":585,"url":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png","type":"image\/png"}],"author":"Oc\u00e9ane PAGNOUX","twitter_card":"summary_large_image","twitter_creator":"@Opisto_fr","twitter_site":"@Opisto_fr","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#article","isPartOf":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/"},"author":{"name":"Oc\u00e9ane PAGNOUX","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/person\/73c1ad08f94cde732413b5ddc363797a"},"headline":"EQUIP AUTO 2022 : une r\u00e9ussite pour Opisto !","datePublished":"2022-11-01T07:00:00+00:00","dateModified":"2022-11-14T10:10:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/"},"wordCount":668,"publisher":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#organization"},"image":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png","keywords":["Communication Opisto"],"articleSection":["2022","Activit\u00e9 d'Opisto","Blog","Ev\u00e9nement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/","url":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/","name":"EQUIP AUTO 2022 : Une r\u00e9ussite pour Opisto \u2013 Opisto","isPartOf":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#primaryimage"},"image":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png","datePublished":"2022-11-01T07:00:00+00:00","dateModified":"2022-11-14T10:10:56+00:00","description":"Clap de fin pour l'\u00e9dition 2022 d'EQUIP AUTO ! Un \u00e9v\u00e8nement auquel participait Opisto, qui a affirm\u00e9 sa position de leader de la distribution en lignes de pi\u00e8ces auto d'occasion aupr\u00e8s des professionnels et centres VHU pr\u00e9sents.","breadcrumb":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#primaryimage","url":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png","contentUrl":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2022\/10\/image00015-1.png","width":1000,"height":585,"caption":"EQUIP AUTO OPISTO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/equip-auto-2022-une-reussite-pour-opisto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.opisto.fr\/fr\/entreprise\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.opisto.fr\/fr\/entreprise\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"EQUIP AUTO 2022 : une r\u00e9ussite pour Opisto !"}]},{"@type":"WebSite","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#website","url":"https:\/\/www.opisto.fr\/fr\/entreprise\/","name":"Opisto","description":"Le sp\u00e9cialiste des pi\u00e8ces auto d\u2019occasion","publisher":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#organization"},"alternateName":"Opisto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.opisto.fr\/fr\/entreprise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#organization","name":"Opisto","alternateName":"Opisto","url":"https:\/\/www.opisto.fr\/fr\/entreprise\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/logo\/image\/","url":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2023\/11\/logo-opisto.svg","contentUrl":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-content\/uploads\/2023\/11\/logo-opisto.svg","width":226,"height":79,"caption":"Opisto"},"image":{"@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/opisto.fr","https:\/\/x.com\/Opisto_fr"]},{"@type":"Person","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/person\/73c1ad08f94cde732413b5ddc363797a","name":"Oc\u00e9ane PAGNOUX","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.opisto.fr\/fr\/entreprise\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0ad6494a29073d76fcaf6fc719942093?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ad6494a29073d76fcaf6fc719942093?s=96&d=mm&r=g","caption":"Oc\u00e9ane PAGNOUX"},"url":"https:\/\/www.opisto.fr\/fr\/entreprise\/author\/oceane\/"}]}},"_links":{"self":[{"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/posts\/3483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/comments?post=3483"}],"version-history":[{"count":3,"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/posts\/3483\/revisions"}],"predecessor-version":[{"id":3508,"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/posts\/3483\/revisions\/3508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/media\/3485"}],"wp:attachment":[{"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/media?parent=3483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/categories?post=3483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opisto.fr\/fr\/entreprise\/wp-json\/wp\/v2\/tags?post=3483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}